{"id":112887,"date":"2025-01-13T11:30:00","date_gmt":"2025-01-13T11:30:00","guid":{"rendered":"https:\/\/www.airpes.com\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/"},"modified":"2022-12-01T17:36:53","modified_gmt":"2022-12-01T17:36:53","slug":"diseno-de-palas-para-aerogeneradores-curiosidades-y-mas","status":"publish","type":"post","link":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/","title":{"rendered":"Dise\u00f1o de palas para aerogeneradores: curiosidades y m\u00e1s"},"content":{"rendered":"<div class=\"wpb_column vc_column_container col-xs-mobile-fullwidth vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"text-block-content hongo-text-block-1 last-paragraph-no-margin\"><h2>Curiosidades, construcci\u00f3n y dise\u00f1o de las palas de los aerogeneradores<\/h2>\n<p>\u00bfTe has preguntado alguna vez c\u00f3mo una torre de aerogenerador puede soportar tanto peso? \u00bfO por qu\u00e9 est\u00e1n todas las palas orientadas en la misma direcci\u00f3n? As\u00ed son las palas de los aerogeneradores, los gigantes de las energ\u00edas renovables.<\/p>\n<p>Seguro que cuando viajas por carretera y te has alejado un poco de la ciudad te has cruzado con un parque e\u00f3lico. Es curioso ver c\u00f3mo las palas de los aerogeneradores parecen trabajar en sincron\u00eda. Es como ver a un equipo de f\u00fatbol, con todos sus miembros estrat\u00e9gicamente colocados y girando en la misma direcci\u00f3n.<\/p>\n<p>Puede parecer una casualidad, pero no lo es:<strong> todos los detalles de su funcionamiento se rigen por razones bien estudiadas y definidas.<\/strong> Vamos a descubrirlas.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-2 last-paragraph-no-margin\"><h3>\u00bfC\u00f3mo funcionan los aerogeneradores?<\/h3>\n<p>Las palas de los aerogeneradores producen <strong>electricidad aprovechando la energ\u00eda natural del viento<\/strong> para impulsar un generador. El viento es una fuente de energ\u00eda limpia y sostenible que nunca se agota, y la transformaci\u00f3n de su energ\u00eda cin\u00e9tica en energ\u00eda el\u00e9ctrica no produce emisiones.<\/p>\n<p>Las palas de los aerogeneradores son la evoluci\u00f3n natural de los molinos de viento y hoy son dispositivos de alta tecnolog\u00eda. Las palas de la mayor\u00eda de las turbinas generan electricidad en cuanto el viento alcanza una velocidad de entre 3 y 4 metros por segundo, generan una potencia m\u00e1xima a 15 metros por segundo y se desconectan para evitar da\u00f1os cuando hay tormentas con vientos que soplan a velocidades medias de m\u00e1s de 25 metros por segundo durante un intervalo temporal de 10 minutos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-110441\" src=\"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\" alt=\"\" width=\"1200\" height=\"628\" \/><\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-3 last-paragraph-no-margin\"><h2>\u00bfPor qu\u00e9 las turbinas e\u00f3licas de tres palas son las m\u00e1s utilizadas?<\/h2>\n<p>A lo largo de la historia se han utilizado muchos tipos de turbinas o m\u00e1quinas para aprovechar la energ\u00eda cin\u00e9tica producida por el viento. De todas ellas, la m\u00e1s utilizada y extendida en la actualidad es la de tres palas que se mueven a lo largo de un eje horizontal. <strong>Es la opci\u00f3n m\u00e1s eficiente desde el punto de vista t\u00e9cnico: cuantas menos palas, mejor es el equilibrio.<\/strong><\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-4 last-paragraph-no-margin\"><h2 data-pm-slice=\"1 1 &#091;&#093;\" data-en-clipboard=\"true\">\u00bfPor qu\u00e9 las palas de los aerogeneradores est\u00e1n siempre orientadas en la misma direcci\u00f3n?<\/h2>\n<div data-pm-slice=\"1 1 &#091;&#093;\" data-en-clipboard=\"true\">Como un campo de girasoles, <strong>los aerogeneradores se orientan siempre en la misma direcci\u00f3n<\/strong> para que, en lugar de seguir al sol, sigan al viento y aprovechen al m\u00e1ximo su energ\u00eda potencial. Esto se consigue mediante una veleta situada en la parte superior de la g\u00f3ndola, que indica al sistema de control si el rotor est\u00e1 correctamente colocado en la direcci\u00f3n del viento.<\/div>\n<div><\/div>\n<blockquote>\n<div>Post relacionado: <a href=\"https:\/\/www.airpes.com\/es\/solucion-integral-instalacion-mantenimiento-palas-eolicas\/\" rev=\"en_rl_none\">Soluci\u00f3n integral para las instalaci\u00f3n y mantenimiento de palas de aerogeneradores<\/a><\/div>\n<\/blockquote>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-110443\" src=\"https:\/\/www.airpes.com\/wp-content\/uploads\/2022\/12\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades-2.jpg\" alt=\"Wind turbine blades: design, curiosities and more - Crosby Airpes\" width=\"1007\" height=\"527\" \/><\/div>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-5 last-paragraph-no-margin\"><h2>Caracter\u00edsticas de un aerogenerador<\/h2>\n<h3>Efecto multiplicador<\/h3>\n<p>El rotor (un conjunto de tres palas montadas en el buje) hace girar un eje lento conectado a una caja de cambios que aumenta la velocidad de rotaci\u00f3n de unas 13 a unas 1.500 revoluciones por minuto.<\/p>\n<h3>Orientaci\u00f3n autom\u00e1tica<\/h3>\n<p>La pala del aerogenerador se orienta autom\u00e1ticamente para <strong>aprovechar al m\u00e1ximo la energ\u00eda cin\u00e9tica del viento<\/strong>, bas\u00e1ndose en los datos registrados por la veleta y el anem\u00f3metro incorporados en la parte superior. La g\u00f3ndola gira sobre una corona situada en el extremo de la torre.<\/p>\n<h3>Generaci\u00f3n de energ\u00eda<\/h3>\n<p>La caja de engranajes, a trav\u00e9s del eje r\u00e1pido, <strong>transfiere su energ\u00eda al generador acoplado<\/strong>, que produce electricidad.<\/p>\n<h3>Velocidad de rotaci\u00f3n de las palas<\/h3>\n<p>El viento hace girar las palas, que comienzan a moverse a velocidades de viento de unos 3,5 m\/s y proporcionan la m\u00e1xima potencia a unos 11 m\/s. Con vientos muy fuertes (25 m\/s) las palas se colocan en bandera y el aerogenerador se ralentiza para evitar esfuerzos excesivos.<\/p>\n<h3>Evacuaci\u00f3n de la energ\u00eda<\/h3>\n<p>La energ\u00eda generada se conduce por el interior de la torre hasta la base y, desde all\u00ed, a trav\u00e9s de una l\u00ednea de metro hasta la subestaci\u00f3n, donde se eleva su tensi\u00f3n para inyectarla en la red el\u00e9ctrica y distribuirla a los puntos de consumo.<\/p>\n<h3>Monitorizaci\u00f3n del sistema<\/h3>\n<p>Todas las funciones cr\u00edticas de las palas del aerogenerador se monitorizan y supervisan desde la subestaci\u00f3n y el centro de control para detectar y resolver cualquier incidencia.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-6 last-paragraph-no-margin\"><h2>Otras preguntas y curiosidades sobre los aerogeneradores<\/h2>\n<p>Algunas de las preguntas m\u00e1s frecuentes sobre el dise\u00f1o de las palas de los aerogeneradores y los parques e\u00f3licos son las siguientes.<\/p>\n<h3>\u00bfC\u00f3mo mueve el viento las palas?<\/h3>\n<p>A veces resulta dif\u00edcil imaginar c\u00f3mo las palas de los aerogeneradores, con semejante tama\u00f1o y peso, consiguen moverse en condiciones normales de viento. La raz\u00f3n radica en su forma, la llamada aerodin\u00e1mica:<strong> cuando el viento incide sobre ellas perpendicularmente, genera una fuerza de sustentaci\u00f3n que las hace moverse.<\/strong><\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-7 last-paragraph-no-margin\"><h3>\u00bfC\u00f3mo soporta la torre tanto peso?<\/h3>\n<p>La torre de un aerogenerador es el componente estructural sobre el que se fijan el rotor y la g\u00f3ndola. Tambi\u00e9n soporta toda la fuerza del viento. <strong>La clave est\u00e1 en su dise\u00f1o y composici\u00f3n,<\/strong> ya que tiene que ser capaz de soportar el peso de hasta 15 elefantes adultos.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-8 last-paragraph-no-margin\"><h3>Material de las palas del aerogenerador<\/h3>\n<p>La mayor\u00eda de las palas est\u00e1n hechas de poli\u00e9ster o de epoxi reforzado con fibra de vidrio. La fibra de carbono o las aramidas (Kevlar) tambi\u00e9n se utilizan como material de refuerzo. Actualmente se est\u00e1 investigando la posibilidad de utilizar compuestos de madera, como madera-epoxi o madera-fibra-epoxi.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-9 last-paragraph-no-margin\"><h3>\u00bfC\u00f3mo se realiza el mantenimiento?<\/h3>\n<p>Existen dos tipos de mantenimiento:<strong> preventivo y correctivo<\/strong>. El primero consiste en inspecciones peri\u00f3dicas para determinar el estado de las palas y encontrar posibles fallos. Estas comprobaciones se realizan con diferentes t\u00e9cnicas: desde el suelo, con teleobjetivos de alta precisi\u00f3n; subiendo a las palas con cuerdas, gr\u00faas o plataformas elevadoras; y a distancia, con drones teledirigidos. El mantenimiento correctivo consiste en reparar o reconstruir las palas y g\u00f3ndolas para reparar los da\u00f1os que aparecen, tanto en la superficie como en su estructura.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb][vc_btn title=\u00bbCROSBY AIRPES PUEDE ENCARGARSE DE LAS PALAS DE TU PARQUE E\u00d3LICO\u00bb style=\u00bbclassic\u00bb shape=\u00bbsquare\u00bb color=\u00bbblack\u00bb align=\u00bbcenter\u00bb link=\u00bburl:https%3A%2F%2Fwww.airpes.com%2Fes%2F5-consejos-de-seguridad-para-el-uso-de-electroimanes%2F|title:Contacta%20Crosby%20Airpes%20ahora|\u00bb][vc_separator color=\u00bbwhite\u00bb][vc_video link=\u00bbhttps:\/\/youtu.be\/ocp1H2dF9EM\u00bb]<div class=\"text-block-content hongo-text-block-10 last-paragraph-no-margin\"><h3>\u00bfC\u00f3mo se reparan las palas?<\/h3>\n<p>Las palas de los aerogeneradores pueden sufrir grietas, da\u00f1os causados por rayos y p\u00e1jaros, o aberturas en el borde de ataque o de salida, entre otros da\u00f1os. Las reparaciones las llevan a cabo <strong>trabajadores en altura<\/strong>, que se cuelgan de las palas con cuerdas o se elevan hasta ellas mediante plataformas suspendidas. Actualmente se est\u00e1n estudiando <strong>sistemas alternativos de reparaci\u00f3n y limpieza,<\/strong> como los drones, para evitar que los operarios tengan que subir a las turbinas.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-11 last-paragraph-no-margin\"><h3>\u00bfC\u00f3mo se decide d\u00f3nde instalar un parque e\u00f3lico?<\/h3>\n<p>Para analizar la viabilidad de un proyecto de energ\u00eda e\u00f3lica, es necesario hacer una evaluaci\u00f3n de cu\u00e1nto producir\u00e1 el parque e\u00f3lico durante su vida \u00fatil. Para ello, una de las principales estimaciones son las caracter\u00edsticas del viento, as\u00ed como la presi\u00f3n y la temperatura del aire. La campa\u00f1a de medici\u00f3n permite transferir los datos extra\u00eddos de cuatro o cinco torres meteorol\u00f3gicas, con mediciones de varios a\u00f1os (2-3) y a diferentes alturas, 50 o 60 metros.<\/p>\n<\/div>[vc_separator color=\u00bbwhite\u00bb]<div class=\"text-block-content hongo-text-block-12 last-paragraph-no-margin\"><h2>Crosby Airpes es su proveedor de equipos para la instalaci\u00f3n y el mantenimiento de sus parques e\u00f3licos.<\/h2>\n<p>Dise\u00f1amos y fabricamos herramientas para tareas especiales de elevaci\u00f3n, instalaci\u00f3n y transporte para la industria e\u00f3lica. Desarrollamos soluciones personalizadas adaptadas a las necesidades de su proyecto.<\/p>\n<\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez te has preguntado c\u00f3mo una torre de un generador e\u00f3lico puede soportar tanto peso? Aqu\u00ed tienes todos los detalles sobre las palas de las turbinas e\u00f3licas. Vamos a verlos.<\/p>\n","protected":false},"author":7,"featured_media":112920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[239],"tags":[],"class_list":["post-112887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-proyectos-eolicos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes<\/title>\n<meta name=\"description\" content=\"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes\" \/>\n<meta property=\"og:description\" content=\"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/\" \/>\n<meta property=\"og:site_name\" content=\"Airpes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AIRPES\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-13T11:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wide-marketing\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@AIRPES\" \/>\n<meta name=\"twitter:site\" content=\"@AIRPES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"wide-marketing\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/\"},\"author\":{\"name\":\"wide-marketing\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#\\\/schema\\\/person\\\/1cdaba084f4ca234033298e712955aa3\"},\"headline\":\"Dise\u00f1o de palas para aerogeneradores: curiosidades y m\u00e1s\",\"datePublished\":\"2025-01-13T11:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/\"},\"wordCount\":1461,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\",\"articleSection\":[\"Proyectos E\u00f3licos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/\",\"url\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/\",\"name\":\"Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\",\"datePublished\":\"2025-01-13T11:30:00+00:00\",\"description\":\"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\",\"contentUrl\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg\",\"width\":1200,\"height\":628,\"caption\":\"Curiosities, construction and transportation of wind turbine blades - Crosby Airpes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dise\u00f1o de palas para aerogeneradores: curiosidades y m\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/\",\"name\":\"Airpes\",\"description\":\"Your lifting equipment supplier\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#organization\",\"name\":\"Airpes\",\"url\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.airpes.com\\\/wp-content\\\/uploads\\\/2020\\\/09\\\/logo.svg\",\"width\":193,\"height\":86,\"caption\":\"Airpes\"},\"image\":{\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AIRPES\",\"https:\\\/\\\/x.com\\\/AIRPES\",\"https:\\\/\\\/www.instagram.com\\\/AIRPESlifting\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/airpes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.airpes.com\\\/es\\\/#\\\/schema\\\/person\\\/1cdaba084f4ca234033298e712955aa3\",\"name\":\"wide-marketing\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes","description":"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/","og_locale":"es_ES","og_type":"article","og_title":"Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes","og_description":"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.","og_url":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/","og_site_name":"Airpes","article_publisher":"https:\/\/www.facebook.com\/AIRPES","article_published_time":"2025-01-13T11:30:00+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg","type":"image\/jpeg"}],"author":"wide-marketing","twitter_card":"summary_large_image","twitter_creator":"@AIRPES","twitter_site":"@AIRPES","twitter_misc":{"Escrito por":"wide-marketing","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#article","isPartOf":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/"},"author":{"name":"wide-marketing","@id":"https:\/\/www.airpes.com\/es\/#\/schema\/person\/1cdaba084f4ca234033298e712955aa3"},"headline":"Dise\u00f1o de palas para aerogeneradores: curiosidades y m\u00e1s","datePublished":"2025-01-13T11:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/"},"wordCount":1461,"commentCount":0,"publisher":{"@id":"https:\/\/www.airpes.com\/es\/#organization"},"image":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg","articleSection":["Proyectos E\u00f3licos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/","url":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/","name":"Palas de aerogeneradores: dise\u00f1o, curiosidades y m\u00e1s - Crosby | Airpes","isPartOf":{"@id":"https:\/\/www.airpes.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#primaryimage"},"image":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg","datePublished":"2025-01-13T11:30:00+00:00","description":"Palas de aerogenerador: dise\u00f1o y m\u00e1s curiosidades sobre ellas. Crosby | Airpes, expertos en soluciones de manipulaci\u00f3n de energ\u00eda e\u00f3lica.","breadcrumb":{"@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#primaryimage","url":"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg","contentUrl":"https:\/\/www.airpes.com\/wp-content\/uploads\/2021\/02\/2212-curiosities-construction-and-transportation-of-wind-turbine-blades.jpg","width":1200,"height":628,"caption":"Curiosities, construction and transportation of wind turbine blades - Crosby Airpes"},{"@type":"BreadcrumbList","@id":"https:\/\/www.airpes.com\/es\/diseno-de-palas-para-aerogeneradores-curiosidades-y-mas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.airpes.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dise\u00f1o de palas para aerogeneradores: curiosidades y m\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/www.airpes.com\/es\/#website","url":"https:\/\/www.airpes.com\/es\/","name":"Airpes","description":"Your lifting equipment supplier","publisher":{"@id":"https:\/\/www.airpes.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.airpes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.airpes.com\/es\/#organization","name":"Airpes","url":"https:\/\/www.airpes.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.airpes.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.airpes.com\/wp-content\/uploads\/2020\/09\/logo.svg","contentUrl":"https:\/\/www.airpes.com\/wp-content\/uploads\/2020\/09\/logo.svg","width":193,"height":86,"caption":"Airpes"},"image":{"@id":"https:\/\/www.airpes.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AIRPES","https:\/\/x.com\/AIRPES","https:\/\/www.instagram.com\/AIRPESlifting\/","https:\/\/www.linkedin.com\/company\/airpes"]},{"@type":"Person","@id":"https:\/\/www.airpes.com\/es\/#\/schema\/person\/1cdaba084f4ca234033298e712955aa3","name":"wide-marketing"}]}},"_links":{"self":[{"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/posts\/112887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/comments?post=112887"}],"version-history":[{"count":4,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/posts\/112887\/revisions"}],"predecessor-version":[{"id":112945,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/posts\/112887\/revisions\/112945"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/media\/112920"}],"wp:attachment":[{"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/media?parent=112887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/categories?post=112887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.airpes.com\/es\/wp-json\/wp\/v2\/tags?post=112887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}